{"id":649,"date":"2014-02-18T15:21:18","date_gmt":"2014-02-18T14:21:18","guid":{"rendered":"http:\/\/www.scuolanobel.it\/?page_id=649"},"modified":"2014-02-18T15:21:18","modified_gmt":"2014-02-18T14:21:18","slug":"istituto-nobel-partner-di-oracle-accademy","status":"publish","type":"page","link":"https:\/\/www.scuolanobel.it\/index.php\/istituto-nobel-partner-di-oracle-accademy\/","title":{"rendered":"Istituto Nobel partner di Oracle Academy"},"content":{"rendered":"<p style=\"text-align: justify;\">L\u2019<strong>istituto Alfred Nobe<\/strong>l\u00a0dall\u2019anno accademico 2013-2014 \u00e8 membro del prestigioso programma di collaborazione con la<strong> Oracle Academy<\/strong>.<\/p>\n<p><a href=\"http:\/\/www.oracle.com\/it\/index.html\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-650 alignnone\" title=\"oracle\" src=\"http:\/\/www.scuolanobel.it\/wp-content\/uploads\/2014\/02\/pngbase642a02b48a502d13f7.png\" alt=\"\" width=\"74\" height=\"74\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><strong>Oracle Corporation<\/strong>\u00a0\u00e8 una societ\u00e0\u00a0di software, con sede in California, nella Silicon Valley. Fu fondata nel 1977\u00a0da Larry Ellison. \u00c8 diventata una potenza nell&#8217;informatica mondiale con il database Oracle, il suo prodotto di punta. L&#8217;azienda conta oggi pi\u00f9 di 200.000 clienti nel mondo ed \u00e8 una delle maggiori imprese nel campo dei database\u00a0e del software in generale.<\/p>\n<p style=\"text-align: justify;\">Nel 2009 Oracle Corporation ha acquisito la societ\u00e0 <strong>Sun Microsystems<\/strong>, l\u2019azienda dove \u00e8 nato il linguaggio <strong>Java<\/strong>.<\/p>\n<p style=\"text-align: justify;\">La Oracle Academy\u00a0\u00e8 un centro di risorse per scuole e studenti online che viene utilizzato in tutto il mondo da oltre 2 milioni di persone.<\/p>\n<p><a href=\"https:\/\/academy.oracle.com\/oa-web-overview.html\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-651\" title=\"Oracle_academy\" src=\"http:\/\/www.scuolanobel.it\/wp-content\/uploads\/2014\/02\/pngbase6440bbf0aaa0f227fd.png\" alt=\"\" width=\"240\" height=\"40\" \/><\/a><\/p>\n<p>Gli alunni dell\u2019istituto Nobel beneficiano\u00a0di:<\/p>\n<ul>\n<li>Software Oracle per scopi didattici<\/li>\n<li>Ambienti di sviluppo Java<\/li>\n<li>Corsi di Formazione online gratuiti<\/li>\n<li>Accesso all\u2019Oracle Magazine e Java Magazine<\/li>\n<li>Accesso a community online e forum tecnici<\/li>\n<li>Sconti su libri ufficiali Oracle<\/li>\n<li>Sconti su percorsi di certificazione Oracle<\/li>\n<li>Accesso a lista degli stage e posti di lavoro disponibili all\u2019Oracle<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019istituto Alfred Nobel\u00a0dall\u2019anno accademico 2013-2014 \u00e8 membro del prestigioso programma di collaborazione con la Oracle Academy. Oracle Corporation\u00a0\u00e8 una societ\u00e0\u00a0di software, con sede in California, nella Silicon Valley. Fu fondata&#8230; <\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/www.scuolanobel.it\/index.php\/wp-json\/wp\/v2\/pages\/649"}],"collection":[{"href":"https:\/\/www.scuolanobel.it\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.scuolanobel.it\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.scuolanobel.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.scuolanobel.it\/index.php\/wp-json\/wp\/v2\/comments?post=649"}],"version-history":[{"count":0,"href":"https:\/\/www.scuolanobel.it\/index.php\/wp-json\/wp\/v2\/pages\/649\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.scuolanobel.it\/index.php\/wp-json\/wp\/v2\/media?parent=649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}